{"id":123,"count":12,"description":"","link":"http:\/\/www.vexploretravel.com\/sites\/category\/vietnam-accommodations\/nha-trang\/nhatrang-deluxe-hotels\/","name":"Nha Trang - Deluxe hotels","slug":"nhatrang-deluxe-hotels","taxonomy":"category","parent":81,"meta":[],"_links":{"self":[{"href":"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/categories\/123"}],"collection":[{"href":"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/categories\/81"}],"wp:post_type":[{"href":"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/posts?categories=123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}