{"id":7472,"date":"2019-04-02T04:39:35","date_gmt":"2019-04-02T04:39:35","guid":{"rendered":"http:\/\/www.vexploretravel.com\/sites\/?p=7472"},"modified":"2019-06-12T09:34:38","modified_gmt":"2019-06-12T09:34:38","slug":"paradise-saigon-boutique-hotel","status":"publish","type":"post","link":"http:\/\/www.vexploretravel.com\/sites\/2019\/04\/02\/paradise-saigon-boutique-hotel\/","title":{"rendered":"Paradise Saigon Boutique Hotel"},"content":{"rendered":"<p><span style=\"color: #000000;\">Class: Standard Class<\/span><\/p>\n<p><span style=\"color: #000000;\">Address: 288 Le Thanh Ton St., Ben Thanh Ward, District 1, Ho Chi Minh City, Vietnam<br \/>\n<\/span><\/p>\n<p><span style=\"color: #000000;\"><!--more--><\/span><\/p>\n<p><span style=\"color: #000000;\">Location: Strategically located in District 1, Paradise Saigon Boutique Hotel is within 300 m from Ben Thanh Market and 350 m from the Reunification Palace; 3.8 km to the Military Museum, while Tan Son Nhat International Airport can be reached within 7 km away.<\/span><\/p>\n<p><iframe loading=\"lazy\" style=\"border: 0;\" src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d3919.5184126834683!2d106.69272361428696!3d10.771549962230328!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x31752f3e914425f1%3A0x463d632470e1271d!2sParadise+Saigon+Boutique+Hotel+%26+Spa!5e0!3m2!1sen!2sus!4v1554179921135!5m2!1sen!2sus\" width=\"600\" height=\"450\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p><span style=\"color: #000000;\">HOTEL DESCRIPTION<\/span><\/p>\n<p><span style=\"color: #000000;\">Luxurious with modern architecture combined between the Eastern and Western decorations, the Saigon Paradise Hotel has been known as the top of its class in the City of Ho Chi Minh. Situated above the 5 meter ceiling of the Paradise&#8217;s lobby is a stunning glass sculpture by 20 people to make. Comprised of 680 hand-blown glass blossoms, it is the largest glass sculpture in the Asia, and certainly one of the most extraordinary. During the day natural sunlight electrifies the vibrant colors of the glass, resulting in a dazzling kaleidoscope that shines across every corner of the lobby.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u00a0<\/span><\/p>\n<p><span style=\"color: #000000;\">ROOM TYPES<\/span><\/p>\n<ul>\n<li><span style=\"color: #000000;\">Deluxe: 25 m<sup>2<\/sup>; offering panoramic views.<\/span><\/li>\n<li><span style=\"color: #000000;\">Premium Deluxe: 30 m\u00b2; offering views of the city<\/span><\/li>\n<li><span style=\"color: #000000;\">Executive Suite: 35 m\u00b2; this suite features air conditioning, a spa bath and panoramic city view<\/span><\/li>\n<li><span style=\"color: #000000;\">Paradise Suite: 45 m\u00b2; this suite features a living room, spa bath and air conditioning<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\">ROOM AMENITIES<\/span><\/p>\n<ul>\n<li><span style=\"color: #000000;\">Non smoking rooms<\/span><\/li>\n<li><span style=\"color: #000000;\">Air conditioning<\/span><\/li>\n<li><span style=\"color: #000000;\">Bathrobes<\/span><\/li>\n<li><span style=\"color: #000000;\">Desk<\/span><\/li>\n<li><span style=\"color: #000000;\">Hair dryer<\/span><\/li>\n<li><span style=\"color: #000000;\">In room safe<\/span><\/li>\n<li><span style=\"color: #000000;\">Television LCD\/plasma screen<\/span><\/li>\n<li><span style=\"color: #000000;\">Shower<\/span><\/li>\n<li><span style=\"color: #000000;\">Mini bar<\/span><\/li>\n<li><span style=\"color: #000000;\">Satellite\/cable TV<\/span><\/li>\n<li><span style=\"color: #000000;\">Coffee\/tea maker<\/span><\/li>\n<li><span style=\"color: #000000;\">Complimentary bottled water<\/span><\/li>\n<li><span style=\"color: #000000;\">Free LAN and WiFi access<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\">FACILITIES AND SERVICES<\/span><\/p>\n<ul>\n<li><span style=\"color: #000000;\">Park View Restaurant: On the top floor, its capacity is up to 100 pax for buffet or cocktail party. Very romantic design, with the panoramic view of the city<\/span><\/li>\n<li><span style=\"color: #000000;\">Business centre<\/span><\/li>\n<li><span style=\"color: #000000;\">Spa<\/span><\/li>\n<li><span style=\"color: #000000;\">Fitness Centre<\/span><\/li>\n<li><span style=\"color: #000000;\">Meeting room<\/span><\/li>\n<li><span style=\"color: #000000;\">Transfer Service<\/span><\/li>\n<\/ul>\n<style id=\"bwg-style-0\">    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails {      width: 754px;              justify-content: center;        margin:0 auto !important;              background-color: rgba(255, 255, 255, 0.00);            padding-left: 4px;      padding-top: 4px;      max-width: 100%;            }        #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item {      justify-content: flex-start;      max-width: 250px;          }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item > a {       margin-right: 4px;       margin-bottom: 4px;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item0 {      padding: 0px;            background-color:rgba(0,0,0, 0.30);      border: 0px none #CCCCCC;      opacity: 1.00;      border-radius: 0;      box-shadow: ;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item1 img {      max-height: none;      max-width: none;      padding: 0 !important;    }         @media only screen and (min-width: 480px) {\t\t#bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item1 img {\t\t\t-webkit-transition: all .3s; transition: all .3s;\t\t}\t\t#bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item1 img:hover {\t\t\t-ms-transform: scale(1.08);\t\t\t-webkit-transform: scale(1.08);\t\t\ttransform: scale(1.08);\t\t}\t\t      }\t    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item1 {      padding-top: 56%;    }        #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-title2,    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-ecommerce2 {      color: #323A45;      font-family: Ubuntu;      font-size: 16px;      font-weight: bold;      padding: 2px;      text-shadow: ;      max-height: 100%;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-thumb-description span {    color: #323A45;    font-family: Ubuntu;    font-size: 12px;    max-height: 100%;    word-wrap: break-word;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-play-icon2 {      font-size: 32px;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-ecommerce2 {      font-size: 19.2px;      color: #323A45;    }    <\/style>    <div id=\"bwg_container1_0\"         class=\"bwg_container bwg_thumbnail bwg_thumbnails\"         data-right-click-protection=\"0\"         data-bwg=\"0\"         data-gallery-type=\"thumbnails\"         data-current-url=\"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/posts\/7472\"         data-lightbox-url=\"http:\/\/www.vexploretravel.com\/sites\/wp-admin\/admin-ajax.php?action=GalleryBox&current_view=0&gallery_id=200&tag=0&theme_id=1&shortcode_id=440&sort_by=order&order_by=asc&current_url=http%3A%2F%2Fwww.vexploretravel.com%2Fsites%2Fwp-json%2Fwp%2Fv2%2Fposts%2F7472\"         data-gallery-id=\"200\"         data-popup-width=\"800\"         data-popup-height=\"500\"         data-is-album=\"gallery\"         data-buttons-position=\"bottom\">      <div id=\"bwg_container2_0\">             <div id=\"ajax_loading_0\" class=\"bwg_loading_div_1\">      <div class=\"bwg_loading_div_2\">        <div class=\"bwg_loading_div_3\">          <div id=\"loading_div_0\" class=\"bwg_spider_ajax_loading\">          <\/div>        <\/div>      <\/div>    <\/div>            <form id=\"gal_front_form_0\"              class=\"bwg-hidden\"              method=\"post\"              action=\"#\"              data-current=\"0\"              data-shortcode-id=\"440\"              data-gallery-type=\"thumbnails\"              data-gallery-id=\"200\"              data-tag=\"0\"              data-album-id=\"0\"              data-theme-id=\"1\"              data-ajax-url=\"http:\/\/www.vexploretravel.com\/sites\/wp-admin\/admin-ajax.php?action=bwg_frontend_data\">          <div id=\"bwg_container3_0\" class=\"bwg-background bwg-background-0\">                <div data-max-count=\"3\"         data-thumbnail-width=\"250\"         data-bwg=\"0\"         data-gallery-id=\"200\"         data-lightbox-url=\"http:\/\/www.vexploretravel.com\/sites\/wp-admin\/admin-ajax.php?action=GalleryBox&current_view=0&gallery_id=200&tag=0&theme_id=1&shortcode_id=440&sort_by=order&order_by=asc&current_url=http%3A%2F%2Fwww.vexploretravel.com%2Fsites%2Fwp-json%2Fwp%2Fv2%2Fposts%2F7472\"         id=\"bwg_thumbnails_0\"         class=\"bwg-container-0 bwg-thumbnails bwg-standard-thumbnails bwg-container bwg-border-box\">            <div class=\"bwg-item\">        <a class=\"bwg-a bwg_lightbox\"  data-image-id=\"2432\" href=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/Paradise_Boutique_SG_1.jpg?bwg=1554181176\" data-elementor-open-lightbox=\"no\" >                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"2432\"                   data-width=\"\"                   data-height=\"\"                   data-original=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Paradise_Boutique_SG_1.jpg?bwg=1554181176\"                   src=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Paradise_Boutique_SG_1.jpg?bwg=1554181176\"                   alt=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>        <div class=\"bwg-thumb-description bwg_thumb_description_0\"><span><\/span><\/div>      <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a bwg_lightbox\"  data-image-id=\"2431\" href=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/Paradise_Boutique_SG_2.jpg?bwg=1554181176\" data-elementor-open-lightbox=\"no\" >                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"2431\"                   data-width=\"\"                   data-height=\"\"                   data-original=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Paradise_Boutique_SG_2.jpg?bwg=1554181176\"                   src=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Paradise_Boutique_SG_2.jpg?bwg=1554181176\"                   alt=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>        <div class=\"bwg-thumb-description bwg_thumb_description_0\"><span><\/span><\/div>      <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a bwg_lightbox\"  data-image-id=\"2430\" href=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/Paradise_Boutique_SG_3.jpg?bwg=1554181176\" data-elementor-open-lightbox=\"no\" >                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"2430\"                   data-width=\"\"                   data-height=\"\"                   data-original=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Paradise_Boutique_SG_3.jpg?bwg=1554181176\"                   src=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Paradise_Boutique_SG_3.jpg?bwg=1554181176\"                   alt=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>        <div class=\"bwg-thumb-description bwg_thumb_description_0\"><span><\/span><\/div>      <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a bwg_lightbox\"  data-image-id=\"2429\" href=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/Paradise_Boutique_SG_4.jpg?bwg=1554181176\" data-elementor-open-lightbox=\"no\" >                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"2429\"                   data-width=\"\"                   data-height=\"\"                   data-original=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Paradise_Boutique_SG_4.jpg?bwg=1554181176\"                   src=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Paradise_Boutique_SG_4.jpg?bwg=1554181176\"                   alt=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>        <div class=\"bwg-thumb-description bwg_thumb_description_0\"><span><\/span><\/div>      <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a bwg_lightbox\"  data-image-id=\"2428\" href=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/Paradise_Boutique_SG_5.jpg?bwg=1554181176\" data-elementor-open-lightbox=\"no\" >                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"2428\"                   data-width=\"\"                   data-height=\"\"                   data-original=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Paradise_Boutique_SG_5.jpg?bwg=1554181176\"                   src=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Paradise_Boutique_SG_5.jpg?bwg=1554181176\"                   alt=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>        <div class=\"bwg-thumb-description bwg_thumb_description_0\"><span><\/span><\/div>      <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a bwg_lightbox\"  data-image-id=\"2427\" href=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/Paradise_Boutique_SG_6.jpg?bwg=1554181176\" data-elementor-open-lightbox=\"no\" >                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"2427\"                   data-width=\"\"                   data-height=\"\"                   data-original=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Paradise_Boutique_SG_6.jpg?bwg=1554181176\"                   src=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Paradise_Boutique_SG_6.jpg?bwg=1554181176\"                   alt=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>        <div class=\"bwg-thumb-description bwg_thumb_description_0\"><span><\/span><\/div>      <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a bwg_lightbox\"  data-image-id=\"2426\" href=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/Paradise_Boutique_SG_7.jpg?bwg=1554181176\" data-elementor-open-lightbox=\"no\" >                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"2426\"                   data-width=\"\"                   data-height=\"\"                   data-original=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Paradise_Boutique_SG_7.jpg?bwg=1554181176\"                   src=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Paradise_Boutique_SG_7.jpg?bwg=1554181176\"                   alt=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>        <div class=\"bwg-thumb-description bwg_thumb_description_0\"><span><\/span><\/div>      <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a bwg_lightbox\"  data-image-id=\"2425\" href=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/Paradise_Boutique_SG_8.jpg?bwg=1554181176\" data-elementor-open-lightbox=\"no\" >                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"2425\"                   data-width=\"\"                   data-height=\"\"                   data-original=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Paradise_Boutique_SG_8.jpg?bwg=1554181176\"                   src=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Paradise_Boutique_SG_8.jpg?bwg=1554181176\"                   alt=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>        <div class=\"bwg-thumb-description bwg_thumb_description_0\"><span><\/span><\/div>      <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a bwg_lightbox\"  data-image-id=\"2424\" href=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/Paradise_Boutique_SG_9.jpg?bwg=1554181176\" data-elementor-open-lightbox=\"no\" >                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"2424\"                   data-width=\"\"                   data-height=\"\"                   data-original=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Paradise_Boutique_SG_9.jpg?bwg=1554181176\"                   src=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Paradise_Boutique_SG_9.jpg?bwg=1554181176\"                   alt=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>        <div class=\"bwg-thumb-description bwg_thumb_description_0\"><span><\/span><\/div>      <\/div>          <\/div>    <style>      \/*pagination styles*\/      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 {\t\t\t\ttext-align: center;\t\t\t\tfont-size: 12px;\t\t\t\tfont-family: Ubuntu;\t\t\t\tfont-weight: bold;\t\t\t\tcolor: #666666;\t\t\t\tmargin: 6px 0 4px;\t\t\t\tdisplay: block;      }      @media only screen and (max-width : 320px) {      #bwg_container1_0 #bwg_container2_0 .displaying-num_0 {     \t display: none;      }      }      #bwg_container1_0 #bwg_container2_0 .displaying-num_0 {\t\t\t\tfont-size: 12px;\t\t\t\tfont-family: Ubuntu;\t\t\t\tfont-weight: bold;\t\t\t\tcolor: #666666;\t\t\t\tmargin-right: 10px;\t\t\t\tvertical-align: middle;      }      #bwg_container1_0 #bwg_container2_0 .paging-input_0 {\t\t\t\tfont-size: 12px;\t\t\t\tfont-family: Ubuntu;\t\t\t\tfont-weight: bold;\t\t\t\tcolor: #666666;\t\t\t\tvertical-align: middle;      }      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 a.disabled,      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 a.disabled:hover,      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 a.disabled:focus,\t\t\t#bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 input.bwg_current_page {\t\t\t\tcursor: default;\t\t\t\tcolor: rgba(102, 102, 102, 0.5);      }      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 a,      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 input.bwg_current_page {\t\t\t\tcursor: pointer;\t\t\t\ttext-align: center;\t\t\t\tfont-size: 12px;\t\t\t\tfont-family: Ubuntu;\t\t\t\tfont-weight: bold;\t\t\t\tcolor: #666666;\t\t\t\ttext-decoration: none;\t\t\t\tpadding: 3px 6px;\t\t\t\tmargin: 0;\t\t\t\tborder-radius: 0;\t\t\t\tborder-style: solid;\t\t\t\tborder-width: 1px;\t\t\t\tborder-color: #E3E3E3;\t\t\t\tbackground-color: #FFFFFF;\t\t\t\topacity: 1.00;\t\t\t\tbox-shadow: 0;\t\t\t\ttransition: all 0.3s ease 0s;-webkit-transition: all 0.3s ease 0s;      }      <\/style>      <span class=\"bwg_nav_cont_0\">              <div class=\"tablenav-pages_0\">                  <\/div>                <input type=\"hidden\" id=\"page_number_0\" name=\"page_number_0\" value=\"1\" \/>      <script type=\"text\/javascript\">        function spider_page_0(cur, x, y, load_more) {          if (typeof load_more == \"undefined\") {            var load_more = false;          }          if (jQuery(cur).hasClass('disabled')) {            return false;          }          var items_county_0 = 1;          switch (y) {            case 1:              if (x >= items_county_0) {                document.getElementById('page_number_0').value = items_county_0;              }              else {                document.getElementById('page_number_0').value = x + 1;              }              break;            case 2:              document.getElementById('page_number_0').value = items_county_0;              break;            case -1:              if (x == 1) {                document.getElementById('page_number_0').value = 1;              }              else {                document.getElementById('page_number_0').value = x - 1;              }              break;            case -2:              document.getElementById('page_number_0').value = 1;              break;\t\t\t\t\t\tcase 0:              document.getElementById('page_number_0').value = x;              break;            default:              document.getElementById('page_number_0').value = 1;          }          bwg_ajax('gal_front_form_0', '0', 'bwg_thumbnails_0', '0', '', 'gallery', 0, '', '', load_more, '', 1);        }                    jQuery('.first-page-0').on('click', function () {              spider_page_0(this, 1, -2, 'numeric');              return false;            });            jQuery('.prev-page-0').on('click', function () {              spider_page_0(this, 1, -1, 'numeric');              return false;            });            jQuery('.next-page-0').on('click', function () {              spider_page_0(this, 1, 1, 'numeric');              return false;            });            jQuery('.last-page-0').on('click', function () {              spider_page_0(this, 1, 2, 'numeric');              return false;            });        \t\t\t\t\/* Change page on input enter. *\/        function bwg_change_page_0( e, that ) {          if (  e.key == 'Enter' ) {            var to_page = parseInt(jQuery(that).val());            var pages_count = jQuery(that).parents(\".pagination-links\").data(\"pages-count\");            var current_url_param = jQuery(that).attr('data-url-info');            if (to_page > pages_count) {              to_page = 1;            }\t \t\t\t\t\t\t\t\t\t\t\t\tspider_page_0(this, to_page, 0, 'numeric');\t\t\t\t\t\t\treturn false;\t\t\t\t\t\t          }          return true;        }        jQuery('.bwg_load_btn_0').on('click', function () {            spider_page_0(this, 1, 1, true);            return false;        });      <\/script>      <\/span>                <\/div>        <\/form>          <style>          #bwg_container1_0 #bwg_container2_0 #spider_popup_overlay_0 {          background-color: #EEEEEE;          opacity: 0.60;          }          <\/style>        <div id=\"bwg_spider_popup_loading_0\" class=\"bwg_spider_popup_loading\"><\/div>        <div id=\"spider_popup_overlay_0\" class=\"spider_popup_overlay\" onclick=\"spider_destroypopup(1000)\"><\/div>        <input type=\"hidden\" id=\"bwg_random_seed_0\" value=\"287936234\">                <\/div>    <\/div>    <script>      if (document.readyState === 'complete') {        if( typeof bwg_main_ready == 'function' ) {          if ( jQuery(\"#bwg_container1_0\").height() ) {            bwg_main_ready(jQuery(\"#bwg_container1_0\"));          }        }      } else {        document.addEventListener('DOMContentLoaded', function() {          if( typeof bwg_main_ready == 'function' ) {            if ( jQuery(\"#bwg_container1_0\").height() ) {             bwg_main_ready(jQuery(\"#bwg_container1_0\"));            }          }        });      }    <\/script>    \n","protected":false},"excerpt":{"rendered":"<p>Class: Standard Class Address: 288 Le Thanh Ton St., Ben Thanh Ward, District 1, Ho Chi Minh City, Vietnam<\/p>\n","protected":false},"author":1,"featured_media":7474,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[109,64,56],"tags":[],"_links":{"self":[{"href":"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/posts\/7472"}],"collection":[{"href":"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/comments?post=7472"}],"version-history":[{"count":2,"href":"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/posts\/7472\/revisions"}],"predecessor-version":[{"id":7477,"href":"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/posts\/7472\/revisions\/7477"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/media\/7474"}],"wp:attachment":[{"href":"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/media?parent=7472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/categories?post=7472"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/tags?post=7472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}