{"id":7514,"date":"2019-04-02T10:04:22","date_gmt":"2019-04-02T10:04:22","guid":{"rendered":"http:\/\/www.vexploretravel.com\/sites\/?p=7514"},"modified":"2019-06-12T09:07:48","modified_gmt":"2019-06-12T09:07:48","slug":"liberty-central-saigon-citypoint","status":"publish","type":"post","link":"http:\/\/www.vexploretravel.com\/sites\/2019\/04\/02\/liberty-central-saigon-citypoint\/","title":{"rendered":"Liberty Central Saigon Citypoint"},"content":{"rendered":"<p><span style=\"color: #000000;\">Class: Superior Class<\/span><\/p>\n<p><span style=\"color: #000000;\">Address: 59 Pasteur, Ben Nghe Ward, District 01, Ho Chi Minh City<br \/>\n<\/span><\/p>\n<p><span style=\"color: #000000;\"><!--more--><\/span><\/p>\n<p><span style=\"color: #000000;\">Location: The hotel is just 200 m from Tax Trade Centre and 300 m from Union Square. Ho Chi Minh City Museum is also 300 m away, while Tan Son Nhat International Airport is accessible with a 7 km drive<\/span><\/p>\n<p><iframe loading=\"lazy\" style=\"border: 0;\" src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m14!1m8!1m3!1d15677.91573587189!2d106.700853!3d10.774583!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x0%3A0x76720b1358eb9260!2sLiberty+Central+Saigon+Citypoint+Hotel!5e0!3m2!1sen!2sus!4v1554199409675!5m2!1sen!2sus\" width=\"600\" height=\"450\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p><span style=\"color: #000000;\">HOTEL DESCRIPTION<\/span><\/p>\n<p><span style=\"color: #000000;\">Embracing a fresh, urban design, Liberty Central Saigon Citypoint\u00a0is an exceptional city hotel that unites convenience and comfort for an unforgettable experience. \u00a0From the moment of arrival, guests can start spoiling themselves by some pampering time at <a style=\"color: #000000;\" href=\"http:\/\/www.libertycentralsaigoncitypoint.com\/en\/facilities\/#home\">The Spa<\/a>, innovative cocktails on <a style=\"color: #000000;\" href=\"http:\/\/www.libertycentralsaigoncitypoint.com\/en\/dining\/#home\">Above Sky Bar<\/a> or refreshing with a dip in our infinity <a style=\"color: #000000;\" href=\"http:\/\/www.libertycentralsaigoncitypoint.com\/en\/facilities\/#home\">rooftop swimming pool<\/a> while indulging in the breathtaking panoramic Saigon skyline views. As the first and only hotel in Ho Chi Minh City that offers an <a style=\"color: #000000;\" href=\"http:\/\/www.libertycentralsaigoncitypoint.com\/en\/facilities\/#home\">in-house cinema<\/a>, guests can also enjoy the latest movie releases in one of our premium cinemas.\u00a0<\/span><\/p>\n<p><span style=\"color: #000000;\">\u00a0<\/span><\/p>\n<p><span style=\"color: #000000;\">ROOM TYPES<\/span><\/p>\n<ul>\n<li><span style=\"color: #000000;\">Deluxe: 22sqm, city view, king-size bed or twin beds, each room is furnished with a wealth of modern facilities and an emphasis on comfort to provide guests a tranquil and relaxing stay.\u00a0<\/span><\/li>\n<li><span style=\"color: #000000;\">Premier City View: 23sqm \u2013 24sqm, city view, king-size bed or twin beds, these rooms offer active city views and expansive skyline, imbuing the space with the inimitable charm of Ho Chi Minh City.<\/span><\/li>\n<li><span style=\"color: #000000;\">Executive: 25sqm \u2013 27sqm, city view, king-size bed or twin beds, the rooms provide guests with exclusive access to our Executive Lounge and a range of additional benefits &amp; services.<\/span><\/li>\n<li><span style=\"color: #000000;\">Signature City View: 27sqm, king-size bed or twin beds, these rooms deliver ultra-comfort that is accompanied by breathtaking views of the city.<\/span><\/li>\n<li><span style=\"color: #000000;\">Liberty Central Suite: 45sqm, one king bed, these suites are the iconic symbol of privileged comfort and convenience being combined perfectly.<\/span><\/li>\n<\/ul>\n<p><span style=\"color: #000000;\"><em>Executive Lounge benefits (for all discerning guests staying at the following room types: Executive, Signature Ocean View, and Liberty Central Suite):<\/em><\/span><\/p>\n<ul>\n<li><span style=\"color: #000000;\">Business computer usage, deluxe turndown service and late check-out till 14:00 (subject to availability).<\/span><br \/>\n<span style=\"color: #000000;\">A private boardroom that is available as a special complimentary benefit for guests to organize meetings with their clients.<\/span><\/li>\n<li><span style=\"color: #000000;\">Breakfast and afternoon tea are served daily, along with an evening cocktail and canap\u00e9 served from 18:30 to 20:30.<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\">ROOM AMENITIES<\/span><\/p>\n<ul>\n<li><span style=\"color: #000000;\">In-room air conditioner<\/span><\/li>\n<li><span style=\"color: #000000;\">Free Wi-Fi access<\/span><\/li>\n<li><span style=\"color: #000000;\">LCD TV with satellite cable channels<\/span><\/li>\n<li><span style=\"color: #000000;\">In-room data port<\/span><\/li>\n<li><span style=\"color: #000000;\">In-room IDD call<\/span><\/li>\n<li><span style=\"color: #000000;\">IDD telephone with extension in bathroom<\/span><\/li>\n<li><span style=\"color: #000000;\">In-room safety deposit box<\/span><\/li>\n<li><span style=\"color: #000000;\">Executive work desk<\/span><\/li>\n<li><span style=\"color: #000000;\">Electric scale<\/span><\/li>\n<li><span style=\"color: #000000;\">Minibar<\/span><\/li>\n<li><span style=\"color: #000000;\">Electric kettle\/ Tea pot<\/span><\/li>\n<li><span style=\"color: #000000;\">Daily mineral water (02 bottles)<\/span><\/li>\n<li><span style=\"color: #000000;\">Slippers\/ Bathrobe\/ Hair dyer<\/span><\/li>\n<li><span style=\"color: #000000;\">Deluxe bathroom amenities<\/span><\/li>\n<li><span style=\"color: #000000;\">Rain shower<\/span><\/li>\n<li><span style=\"color: #000000;\">Black-out curtain<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\">DINING<\/span><\/p>\n<ul>\n<li><span style=\"color: #000000;\">Central Restaurant: an outstanding place for guests to either enjoy their nutritious breakfast or treat themselves to a distinctive selection of cuisines.<\/span><\/li>\n<li><span style=\"color: #000000;\">The Bistro: an accommodating destination for guests meeting up with business partners, catching up with friends or simply tucking in a good book.<\/span><\/li>\n<li><span style=\"color: #000000;\">Above Sky Bar: offers an innovative selection of high-end spirits, signature cocktails, draught beers and fine wines, all complimented by a carefully curated menu of light snacks.<\/span><\/li>\n<li><span style=\"color: #000000;\">Libra Dining Room: an intimate atmosphere and cosy dining experience for several types of events, such as: birthdays, anniversaries, bridal showers and rehearsal dinners.<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\">FACILITIES AND SERVICES<\/span><\/p>\n<ul>\n<li><span style=\"color: #000000;\">Executive Lounge<\/span><\/li>\n<li><span style=\"color: #000000;\">Swimming pool<\/span><\/li>\n<li><span style=\"color: #000000;\">Fitness Centre<\/span><\/li>\n<li><span style=\"color: #000000;\">Spa<\/span><\/li>\n<li><span style=\"color: #000000;\">Cinema<\/span><\/li>\n<\/ul>\n<style id=\"bwg-style-0\">    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails {      width: 754px;              justify-content: center;        margin:0 auto !important;              background-color: rgba(255, 255, 255, 0.00);            padding-left: 4px;      padding-top: 4px;      max-width: 100%;            }        #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item {      justify-content: flex-start;      max-width: 250px;          }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item > a {       margin-right: 4px;       margin-bottom: 4px;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item0 {      padding: 0px;            background-color:rgba(0,0,0, 0.30);      border: 0px none #CCCCCC;      opacity: 1.00;      border-radius: 0;      box-shadow: ;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item1 img {      max-height: none;      max-width: none;      padding: 0 !important;    }         @media only screen and (min-width: 480px) {\t\t#bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item1 img {\t\t\t-webkit-transition: all .3s; transition: all .3s;\t\t}\t\t#bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item1 img:hover {\t\t\t-ms-transform: scale(1.08);\t\t\t-webkit-transform: scale(1.08);\t\t\ttransform: scale(1.08);\t\t}\t\t      }\t    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item1 {      padding-top: 56%;    }        #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-title2,    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-ecommerce2 {      color: #323A45;      font-family: Ubuntu;      font-size: 16px;      font-weight: bold;      padding: 2px;      text-shadow: ;      max-height: 100%;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-thumb-description span {    color: #323A45;    font-family: Ubuntu;    font-size: 12px;    max-height: 100%;    word-wrap: break-word;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-play-icon2 {      font-size: 32px;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-ecommerce2 {      font-size: 19.2px;      color: #323A45;    }    <\/style>    <div id=\"bwg_container1_0\"         class=\"bwg_container bwg_thumbnail bwg_thumbnails\"         data-right-click-protection=\"0\"         data-bwg=\"0\"         data-gallery-type=\"thumbnails\"         data-current-url=\"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/posts\/7514\"         data-lightbox-url=\"http:\/\/www.vexploretravel.com\/sites\/wp-admin\/admin-ajax.php?action=GalleryBox&current_view=0&gallery_id=206&tag=0&theme_id=1&shortcode_id=453&sort_by=order&order_by=asc&current_url=http%3A%2F%2Fwww.vexploretravel.com%2Fsites%2Fwp-json%2Fwp%2Fv2%2Fposts%2F7514\"         data-gallery-id=\"206\"         data-popup-width=\"800\"         data-popup-height=\"500\"         data-is-album=\"gallery\"         data-buttons-position=\"bottom\">      <div id=\"bwg_container2_0\">             <div id=\"ajax_loading_0\" class=\"bwg_loading_div_1\">      <div class=\"bwg_loading_div_2\">        <div class=\"bwg_loading_div_3\">          <div id=\"loading_div_0\" class=\"bwg_spider_ajax_loading\">          <\/div>        <\/div>      <\/div>    <\/div>            <form id=\"gal_front_form_0\"              class=\"bwg-hidden\"              method=\"post\"              action=\"#\"              data-current=\"0\"              data-shortcode-id=\"453\"              data-gallery-type=\"thumbnails\"              data-gallery-id=\"206\"              data-tag=\"0\"              data-album-id=\"0\"              data-theme-id=\"1\"              data-ajax-url=\"http:\/\/www.vexploretravel.com\/sites\/wp-admin\/admin-ajax.php?action=bwg_frontend_data\">          <div id=\"bwg_container3_0\" class=\"bwg-background bwg-background-0\">                <div data-max-count=\"3\"         data-thumbnail-width=\"250\"         data-bwg=\"0\"         data-gallery-id=\"206\"         data-lightbox-url=\"http:\/\/www.vexploretravel.com\/sites\/wp-admin\/admin-ajax.php?action=GalleryBox&current_view=0&gallery_id=206&tag=0&theme_id=1&shortcode_id=453&sort_by=order&order_by=asc&current_url=http%3A%2F%2Fwww.vexploretravel.com%2Fsites%2Fwp-json%2Fwp%2Fv2%2Fposts%2F7514\"         id=\"bwg_thumbnails_0\"         class=\"bwg-container-0 bwg-thumbnails bwg-standard-thumbnails bwg-container bwg-border-box\">            <div class=\"bwg-item\">        <a class=\"bwg-a bwg_lightbox\"  data-image-id=\"2493\" href=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/Liberty_Central_1.jpg?bwg=1554199855\" data-elementor-open-lightbox=\"no\" >                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"2493\"                   data-width=\"\"                   data-height=\"\"                   data-original=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Liberty_Central_1.jpg?bwg=1554199855\"                   src=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Liberty_Central_1.jpg?bwg=1554199855\"                   alt=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>        <div class=\"bwg-thumb-description bwg_thumb_description_0\"><span><\/span><\/div>      <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a bwg_lightbox\"  data-image-id=\"2492\" href=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/Liberty_Central_2.jpg?bwg=1554199855\" data-elementor-open-lightbox=\"no\" >                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"2492\"                   data-width=\"\"                   data-height=\"\"                   data-original=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Liberty_Central_2.jpg?bwg=1554199855\"                   src=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Liberty_Central_2.jpg?bwg=1554199855\"                   alt=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>        <div class=\"bwg-thumb-description bwg_thumb_description_0\"><span><\/span><\/div>      <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a bwg_lightbox\"  data-image-id=\"2491\" href=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/Liberty_Central_3.jpg?bwg=1554199855\" data-elementor-open-lightbox=\"no\" >                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"2491\"                   data-width=\"\"                   data-height=\"\"                   data-original=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Liberty_Central_3.jpg?bwg=1554199855\"                   src=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Liberty_Central_3.jpg?bwg=1554199855\"                   alt=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>        <div class=\"bwg-thumb-description bwg_thumb_description_0\"><span><\/span><\/div>      <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a bwg_lightbox\"  data-image-id=\"2490\" href=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/Liberty_Central_4.jpg?bwg=1554199855\" data-elementor-open-lightbox=\"no\" >                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"2490\"                   data-width=\"\"                   data-height=\"\"                   data-original=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Liberty_Central_4.jpg?bwg=1554199855\"                   src=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Liberty_Central_4.jpg?bwg=1554199855\"                   alt=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>        <div class=\"bwg-thumb-description bwg_thumb_description_0\"><span><\/span><\/div>      <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a bwg_lightbox\"  data-image-id=\"2489\" href=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/Liberty_Central_5.jpg?bwg=1554199855\" data-elementor-open-lightbox=\"no\" >                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"2489\"                   data-width=\"\"                   data-height=\"\"                   data-original=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Liberty_Central_5.jpg?bwg=1554199855\"                   src=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Liberty_Central_5.jpg?bwg=1554199855\"                   alt=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>        <div class=\"bwg-thumb-description bwg_thumb_description_0\"><span><\/span><\/div>      <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a bwg_lightbox\"  data-image-id=\"2488\" href=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/Liberty_Central_6.jpg?bwg=1554199855\" data-elementor-open-lightbox=\"no\" >                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"2488\"                   data-width=\"\"                   data-height=\"\"                   data-original=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Liberty_Central_6.jpg?bwg=1554199855\"                   src=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Liberty_Central_6.jpg?bwg=1554199855\"                   alt=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>        <div class=\"bwg-thumb-description bwg_thumb_description_0\"><span><\/span><\/div>      <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a bwg_lightbox\"  data-image-id=\"2487\" href=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/Liberty_Central_7.jpg?bwg=1554199855\" data-elementor-open-lightbox=\"no\" >                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"2487\"                   data-width=\"\"                   data-height=\"\"                   data-original=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Liberty_Central_7.jpg?bwg=1554199855\"                   src=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Liberty_Central_7.jpg?bwg=1554199855\"                   alt=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>        <div class=\"bwg-thumb-description bwg_thumb_description_0\"><span><\/span><\/div>      <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a bwg_lightbox\"  data-image-id=\"2486\" href=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/Liberty_Central_8.jpg?bwg=1554199855\" data-elementor-open-lightbox=\"no\" >                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"2486\"                   data-width=\"\"                   data-height=\"\"                   data-original=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Liberty_Central_8.jpg?bwg=1554199855\"                   src=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Liberty_Central_8.jpg?bwg=1554199855\"                   alt=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>        <div class=\"bwg-thumb-description bwg_thumb_description_0\"><span><\/span><\/div>      <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a bwg_lightbox\"  data-image-id=\"2485\" href=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/Liberty_Central_9.jpg?bwg=1554199855\" data-elementor-open-lightbox=\"no\" >                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"2485\"                   data-width=\"\"                   data-height=\"\"                   data-original=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Liberty_Central_9.jpg?bwg=1554199855\"                   src=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Liberty_Central_9.jpg?bwg=1554199855\"                   alt=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>        <div class=\"bwg-thumb-description bwg_thumb_description_0\"><span><\/span><\/div>      <\/div>          <\/div>    <style>      \/*pagination styles*\/      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 {\t\t\t\ttext-align: center;\t\t\t\tfont-size: 12px;\t\t\t\tfont-family: Ubuntu;\t\t\t\tfont-weight: bold;\t\t\t\tcolor: #666666;\t\t\t\tmargin: 6px 0 4px;\t\t\t\tdisplay: block;      }      @media only screen and (max-width : 320px) {      #bwg_container1_0 #bwg_container2_0 .displaying-num_0 {     \t display: none;      }      }      #bwg_container1_0 #bwg_container2_0 .displaying-num_0 {\t\t\t\tfont-size: 12px;\t\t\t\tfont-family: Ubuntu;\t\t\t\tfont-weight: bold;\t\t\t\tcolor: #666666;\t\t\t\tmargin-right: 10px;\t\t\t\tvertical-align: middle;      }      #bwg_container1_0 #bwg_container2_0 .paging-input_0 {\t\t\t\tfont-size: 12px;\t\t\t\tfont-family: Ubuntu;\t\t\t\tfont-weight: bold;\t\t\t\tcolor: #666666;\t\t\t\tvertical-align: middle;      }      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 a.disabled,      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 a.disabled:hover,      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 a.disabled:focus,\t\t\t#bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 input.bwg_current_page {\t\t\t\tcursor: default;\t\t\t\tcolor: rgba(102, 102, 102, 0.5);      }      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 a,      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 input.bwg_current_page {\t\t\t\tcursor: pointer;\t\t\t\ttext-align: center;\t\t\t\tfont-size: 12px;\t\t\t\tfont-family: Ubuntu;\t\t\t\tfont-weight: bold;\t\t\t\tcolor: #666666;\t\t\t\ttext-decoration: none;\t\t\t\tpadding: 3px 6px;\t\t\t\tmargin: 0;\t\t\t\tborder-radius: 0;\t\t\t\tborder-style: solid;\t\t\t\tborder-width: 1px;\t\t\t\tborder-color: #E3E3E3;\t\t\t\tbackground-color: #FFFFFF;\t\t\t\topacity: 1.00;\t\t\t\tbox-shadow: 0;\t\t\t\ttransition: all 0.3s ease 0s;-webkit-transition: all 0.3s ease 0s;      }      <\/style>      <span class=\"bwg_nav_cont_0\">              <div class=\"tablenav-pages_0\">                  <\/div>                <input type=\"hidden\" id=\"page_number_0\" name=\"page_number_0\" value=\"1\" \/>      <script type=\"text\/javascript\">        function spider_page_0(cur, x, y, load_more) {          if (typeof load_more == \"undefined\") {            var load_more = false;          }          if (jQuery(cur).hasClass('disabled')) {            return false;          }          var items_county_0 = 1;          switch (y) {            case 1:              if (x >= items_county_0) {                document.getElementById('page_number_0').value = items_county_0;              }              else {                document.getElementById('page_number_0').value = x + 1;              }              break;            case 2:              document.getElementById('page_number_0').value = items_county_0;              break;            case -1:              if (x == 1) {                document.getElementById('page_number_0').value = 1;              }              else {                document.getElementById('page_number_0').value = x - 1;              }              break;            case -2:              document.getElementById('page_number_0').value = 1;              break;\t\t\t\t\t\tcase 0:              document.getElementById('page_number_0').value = x;              break;            default:              document.getElementById('page_number_0').value = 1;          }          bwg_ajax('gal_front_form_0', '0', 'bwg_thumbnails_0', '0', '', 'gallery', 0, '', '', load_more, '', 1);        }                    jQuery('.first-page-0').on('click', function () {              spider_page_0(this, 1, -2, 'numeric');              return false;            });            jQuery('.prev-page-0').on('click', function () {              spider_page_0(this, 1, -1, 'numeric');              return false;            });            jQuery('.next-page-0').on('click', function () {              spider_page_0(this, 1, 1, 'numeric');              return false;            });            jQuery('.last-page-0').on('click', function () {              spider_page_0(this, 1, 2, 'numeric');              return false;            });        \t\t\t\t\/* Change page on input enter. *\/        function bwg_change_page_0( e, that ) {          if (  e.key == 'Enter' ) {            var to_page = parseInt(jQuery(that).val());            var pages_count = jQuery(that).parents(\".pagination-links\").data(\"pages-count\");            var current_url_param = jQuery(that).attr('data-url-info');            if (to_page > pages_count) {              to_page = 1;            }\t \t\t\t\t\t\t\t\t\t\t\t\tspider_page_0(this, to_page, 0, 'numeric');\t\t\t\t\t\t\treturn false;\t\t\t\t\t\t          }          return true;        }        jQuery('.bwg_load_btn_0').on('click', function () {            spider_page_0(this, 1, 1, true);            return false;        });      <\/script>      <\/span>                <\/div>        <\/form>          <style>          #bwg_container1_0 #bwg_container2_0 #spider_popup_overlay_0 {          background-color: #EEEEEE;          opacity: 0.60;          }          <\/style>        <div id=\"bwg_spider_popup_loading_0\" class=\"bwg_spider_popup_loading\"><\/div>        <div id=\"spider_popup_overlay_0\" class=\"spider_popup_overlay\" onclick=\"spider_destroypopup(1000)\"><\/div>        <input type=\"hidden\" id=\"bwg_random_seed_0\" value=\"1520449309\">                <\/div>    <\/div>    <script>      if (document.readyState === 'complete') {        if( typeof bwg_main_ready == 'function' ) {          if ( jQuery(\"#bwg_container1_0\").height() ) {            bwg_main_ready(jQuery(\"#bwg_container1_0\"));          }        }      } else {        document.addEventListener('DOMContentLoaded', function() {          if( typeof bwg_main_ready == 'function' ) {            if ( jQuery(\"#bwg_container1_0\").height() ) {             bwg_main_ready(jQuery(\"#bwg_container1_0\"));            }          }        });      }    <\/script>    \n","protected":false},"excerpt":{"rendered":"<p>Class: Superior Class Address: 59 Pasteur, Ben Nghe Ward, District 01, Ho Chi Minh City<\/p>\n","protected":false},"author":1,"featured_media":7516,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[110,64,56],"tags":[],"_links":{"self":[{"href":"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/posts\/7514"}],"collection":[{"href":"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/comments?post=7514"}],"version-history":[{"count":2,"href":"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/posts\/7514\/revisions"}],"predecessor-version":[{"id":7520,"href":"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/posts\/7514\/revisions\/7520"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/media\/7516"}],"wp:attachment":[{"href":"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/media?parent=7514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/categories?post=7514"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/tags?post=7514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}