{"id":8475,"date":"2019-05-07T09:46:28","date_gmt":"2019-05-07T09:46:28","guid":{"rendered":"http:\/\/www.vexploretravel.com\/sites\/?p=8475"},"modified":"2019-06-12T10:00:05","modified_gmt":"2019-06-12T10:00:05","slug":"muong-thanh-holiday-hue","status":"publish","type":"post","link":"http:\/\/www.vexploretravel.com\/sites\/2019\/05\/07\/muong-thanh-holiday-hue\/","title":{"rendered":"Muong Thanh Holiday Hue"},"content":{"rendered":"<p><span style=\"color: #000000;\">Class: Superior Class \u00a0<\/span><\/p>\n<p><span style=\"color: #000000;\">Address: No 38 &#8211; Le Loi &#8211; Hue city &#8211; Viet Nam<br \/>\n<\/span><\/p>\n<p><span style=\"color: #000000;\"><!--more--><\/span><\/p>\n<p><span style=\"color: #000000;\">Location: Muong Thanh Holiday Hue Hotel boasts its proximity to the Phu Bai Airport and many other attractions in the city. Right across from the hotel is the Hue Ferry Terminal where guests can get on to explore the city in an unconventional way.<\/span><\/p>\n<p><iframe loading=\"lazy\" style=\"border: 0;\" src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d3826.1205399717546!2d107.59099295069554!3d16.469432988579097!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x3141a13cb6ac8431%3A0x4b9904d7eb09b194!2sMuong+Thanh+Holiday+Hue+Hotel!5e0!3m2!1sen!2sus!4v1557222364609!5m2!1sen!2sus\" width=\"600\" height=\"450\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p><span style=\"color: #000000;\">HOTEL DESCRIPTION<\/span><\/p>\n<p><span style=\"color: #000000;\">Located on green Le Loi street right in the city center and poetic Perfume River bank, Muong Thanh Holiday Hue features a panoramic picture of Hue City, Perfume River, Trang Tien bridge and ancient Hue citadel. From the hotel, you can walk to the night market or other famous sightseeing of Hue. As a symbol of the harmonic combination between classic and modern architecture and culture, Muong Thanh Holiday Hue represents ancient Hue cultural fair and offers a peaceful space for resting and relaxing.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\">ROOM TYPES<\/span><\/p>\n<p><span style=\"color: #000000;\">Muong Thanh Holiday Hue has 108 guest rooms with luxurious living space, cozy furniture and world-class amenities.<\/span><\/p>\n<ul>\n<li><span style=\"color: #000000;\">Deluxe King: 32 sqm, city\/river view<\/span><\/li>\n<li><span style=\"color: #000000;\">Premium Deluxe King: 45 sqm, balcony with river view<\/span><\/li>\n<li><span style=\"color: #000000;\">Executive Suite: 60 sqm, located on the 10th floor, river view<\/span><\/li>\n<li><span style=\"color: #000000;\">Grand Suite: 60 sqm, located on 9th floor, view to Perfume river and Truong Tien bridge<\/span><\/li>\n<li><span style=\"color: #000000;\">Pool Villa: 235 sqm, private pool with sunlounges, river view<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\">ROOM AMENITIES<\/span><\/p>\n<ul>\n<li><span style=\"color: #000000;\">Individual controlled air-condition<\/span><\/li>\n<li><span style=\"color: #000000;\">Complimentary high speed internet<\/span><\/li>\n<li><span style=\"color: #000000;\">Satellite TV<\/span><\/li>\n<li><span style=\"color: #000000;\">IDD telephone<\/span><\/li>\n<li><span style=\"color: #000000;\">Mineral water, tea and coffee<\/span><\/li>\n<li><span style=\"color: #000000;\">Work desk<\/span><\/li>\n<li><span style=\"color: #000000;\">Wardrobe\/Hair dryer<\/span><\/li>\n<li><span style=\"color: #000000;\">Slippers\/Bathrobe<\/span><\/li>\n<li><span style=\"color: #000000;\">Toothbrush\/Comb<\/span><\/li>\n<li><span style=\"color: #000000;\">Cotton buds\/Bathing-cap\/Sanitary bag<\/span><\/li>\n<li><span style=\"color: #000000;\">Bath gel\/Shampoo\/Skin cream<\/span><\/li>\n<li><span style=\"color: #000000;\">Kettle (Executive Suite over)<\/span><\/li>\n<li><span style=\"color: #000000;\">Coffee making facilities (Executive Suite over)<\/span><\/li>\n<li><span style=\"color: #000000;\">Refrigerator (Executive Suite over)<\/span><\/li>\n<li><span style=\"color: #000000;\">In-room safe (Grand Suite over)<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\">DINING <\/span><\/p>\n<ul>\n<li><span style=\"color: #000000;\">Kim Long restaurant: Kim Long restaurant is an ideal place for a party with friends and family.<\/span><\/li>\n<li><span style=\"color: #000000;\">An Hoa Restaurant: A variety of Vietnamese and International specialities. An Hoa restaurant is an ideal place for wedding or gala.<\/span><\/li>\n<li><span style=\"color: #000000;\">Gia Hoi Bar: A unique place on the 11th floor to unwind your hectic day, sipping a chilled beer or a cocktail of your choice.<\/span><\/li>\n<li><span style=\"color: #000000;\">An Hien Bar &amp; Caf\u00e9: Let&#8217;s enjoy premium drinks and special light food in an airy and comfortable space of Hue in An Hien Bar &amp; Cafe.<\/span><\/li>\n<li><span style=\"color: #000000;\">An Cuu Restaurant: An Cuu restaurant serves breakfast buffet, Asian-European specialties, fresh salad and various desserts.<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\">FACILITIES AND SERVICES<\/span><\/p>\n<ul>\n<li><span style=\"color: #000000;\">Swimming Pool<\/span><\/li>\n<li><span style=\"color: #000000;\">Fitness Centre<\/span><\/li>\n<li><span style=\"color: #000000;\">Spa<\/span><\/li>\n<li><span style=\"color: #000000;\">Transportation service<\/span><\/li>\n<li><span style=\"color: #000000;\">Baby sister service<\/span><\/li>\n<li><span style=\"color: #000000;\">Tours and Excursions<\/span><\/li>\n<li><span style=\"color: #000000;\">Currency exchange<\/span><\/li>\n<li><span style=\"color: #000000;\">Room Service 24\/24<\/span><\/li>\n<li><span style=\"color: #000000;\">Airline bookable service<\/span><\/li>\n<li><span style=\"color: #000000;\">Laundry service<\/span><\/li>\n<li><span style=\"color: #000000;\">Photocopy and secretary services<\/span><\/li>\n<li><span style=\"color: #000000;\">Boutique shop.<\/span><\/li>\n<li><span style=\"color: #000000;\">Car rental service<\/span><\/li>\n<\/ul>\n<style id=\"bwg-style-0\">    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails {      width: 754px;              justify-content: center;        margin:0 auto !important;              background-color: rgba(255, 255, 255, 0.00);            padding-left: 4px;      padding-top: 4px;      max-width: 100%;            }        #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item {      justify-content: flex-start;      max-width: 250px;          }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item > a {       margin-right: 4px;       margin-bottom: 4px;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item0 {      padding: 0px;            background-color:rgba(0,0,0, 0.30);      border: 0px none #CCCCCC;      opacity: 1.00;      border-radius: 0;      box-shadow: ;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item1 img {      max-height: none;      max-width: none;      padding: 0 !important;    }         @media only screen and (min-width: 480px) {\t\t#bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item1 img {\t\t\t-webkit-transition: all .3s; transition: all .3s;\t\t}\t\t#bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item1 img:hover {\t\t\t-ms-transform: scale(1.08);\t\t\t-webkit-transform: scale(1.08);\t\t\ttransform: scale(1.08);\t\t}\t\t      }\t    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item1 {      padding-top: 56%;    }        #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-title2,    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-ecommerce2 {      color: #323A45;      font-family: Ubuntu;      font-size: 16px;      font-weight: bold;      padding: 2px;      text-shadow: ;      max-height: 100%;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-thumb-description span {    color: #323A45;    font-family: Ubuntu;    font-size: 12px;    max-height: 100%;    word-wrap: break-word;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-play-icon2 {      font-size: 32px;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-ecommerce2 {      font-size: 19.2px;      color: #323A45;    }    <\/style>    <div id=\"bwg_container1_0\"         class=\"bwg_container bwg_thumbnail bwg_thumbnails\"         data-right-click-protection=\"0\"         data-bwg=\"0\"         data-gallery-type=\"thumbnails\"         data-current-url=\"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/posts\/8475\"         data-lightbox-url=\"http:\/\/www.vexploretravel.com\/sites\/wp-admin\/admin-ajax.php?action=GalleryBox&current_view=0&gallery_id=359&tag=0&theme_id=1&shortcode_id=763&sort_by=order&order_by=asc&current_url=http%3A%2F%2Fwww.vexploretravel.com%2Fsites%2Fwp-json%2Fwp%2Fv2%2Fposts%2F8475\"         data-gallery-id=\"359\"         data-popup-width=\"800\"         data-popup-height=\"500\"         data-is-album=\"gallery\"         data-buttons-position=\"bottom\">      <div id=\"bwg_container2_0\">             <div id=\"ajax_loading_0\" class=\"bwg_loading_div_1\">      <div class=\"bwg_loading_div_2\">        <div class=\"bwg_loading_div_3\">          <div id=\"loading_div_0\" class=\"bwg_spider_ajax_loading\">          <\/div>        <\/div>      <\/div>    <\/div>            <form id=\"gal_front_form_0\"              class=\"bwg-hidden\"              method=\"post\"              action=\"#\"              data-current=\"0\"              data-shortcode-id=\"763\"              data-gallery-type=\"thumbnails\"              data-gallery-id=\"359\"              data-tag=\"0\"              data-album-id=\"0\"              data-theme-id=\"1\"              data-ajax-url=\"http:\/\/www.vexploretravel.com\/sites\/wp-admin\/admin-ajax.php?action=bwg_frontend_data\">          <div id=\"bwg_container3_0\" class=\"bwg-background bwg-background-0\">                <div data-max-count=\"3\"         data-thumbnail-width=\"250\"         data-bwg=\"0\"         data-gallery-id=\"359\"         data-lightbox-url=\"http:\/\/www.vexploretravel.com\/sites\/wp-admin\/admin-ajax.php?action=GalleryBox&current_view=0&gallery_id=359&tag=0&theme_id=1&shortcode_id=763&sort_by=order&order_by=asc&current_url=http%3A%2F%2Fwww.vexploretravel.com%2Fsites%2Fwp-json%2Fwp%2Fv2%2Fposts%2F8475\"         id=\"bwg_thumbnails_0\"         class=\"bwg-container-0 bwg-thumbnails bwg-standard-thumbnails bwg-container bwg-border-box\">            <div class=\"bwg-item\">        <a class=\"bwg-a bwg_lightbox\"  data-image-id=\"3861\" href=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/Muong_Thanh_Hue_1.jpg?bwg=1557223082\" data-elementor-open-lightbox=\"no\" >                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"3861\"                   data-width=\"\"                   data-height=\"\"                   data-original=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Muong_Thanh_Hue_1.jpg?bwg=1557223082\"                   src=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Muong_Thanh_Hue_1.jpg?bwg=1557223082\"                   alt=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>        <div class=\"bwg-thumb-description bwg_thumb_description_0\"><span><\/span><\/div>      <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a bwg_lightbox\"  data-image-id=\"3860\" href=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/Muong_Thanh_Hue_2.jpg?bwg=1557223082\" data-elementor-open-lightbox=\"no\" >                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"3860\"                   data-width=\"\"                   data-height=\"\"                   data-original=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Muong_Thanh_Hue_2.jpg?bwg=1557223082\"                   src=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Muong_Thanh_Hue_2.jpg?bwg=1557223082\"                   alt=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>        <div class=\"bwg-thumb-description bwg_thumb_description_0\"><span><\/span><\/div>      <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a bwg_lightbox\"  data-image-id=\"3859\" href=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/Muong_Thanh_Hue_3.jpg?bwg=1557223082\" data-elementor-open-lightbox=\"no\" >                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"3859\"                   data-width=\"\"                   data-height=\"\"                   data-original=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Muong_Thanh_Hue_3.jpg?bwg=1557223082\"                   src=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Muong_Thanh_Hue_3.jpg?bwg=1557223082\"                   alt=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>        <div class=\"bwg-thumb-description bwg_thumb_description_0\"><span><\/span><\/div>      <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a bwg_lightbox\"  data-image-id=\"3858\" href=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/Muong_Thanh_Hue_4.jpg?bwg=1557223082\" data-elementor-open-lightbox=\"no\" >                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"3858\"                   data-width=\"\"                   data-height=\"\"                   data-original=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Muong_Thanh_Hue_4.jpg?bwg=1557223082\"                   src=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Muong_Thanh_Hue_4.jpg?bwg=1557223082\"                   alt=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>        <div class=\"bwg-thumb-description bwg_thumb_description_0\"><span><\/span><\/div>      <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a bwg_lightbox\"  data-image-id=\"3857\" href=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/Muong_Thanh_Hue_5.jpg?bwg=1557223082\" data-elementor-open-lightbox=\"no\" >                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"3857\"                   data-width=\"\"                   data-height=\"\"                   data-original=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Muong_Thanh_Hue_5.jpg?bwg=1557223082\"                   src=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Muong_Thanh_Hue_5.jpg?bwg=1557223082\"                   alt=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>        <div class=\"bwg-thumb-description bwg_thumb_description_0\"><span><\/span><\/div>      <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a bwg_lightbox\"  data-image-id=\"3856\" href=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/Muong_Thanh_Hue_6.jpg?bwg=1557223082\" data-elementor-open-lightbox=\"no\" >                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"3856\"                   data-width=\"\"                   data-height=\"\"                   data-original=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Muong_Thanh_Hue_6.jpg?bwg=1557223082\"                   src=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Muong_Thanh_Hue_6.jpg?bwg=1557223082\"                   alt=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>        <div class=\"bwg-thumb-description bwg_thumb_description_0\"><span><\/span><\/div>      <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a bwg_lightbox\"  data-image-id=\"3855\" href=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/Muong_Thanh_Hue_7.jpg?bwg=1557223082\" data-elementor-open-lightbox=\"no\" >                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"3855\"                   data-width=\"\"                   data-height=\"\"                   data-original=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Muong_Thanh_Hue_7.jpg?bwg=1557223082\"                   src=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Muong_Thanh_Hue_7.jpg?bwg=1557223082\"                   alt=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>        <div class=\"bwg-thumb-description bwg_thumb_description_0\"><span><\/span><\/div>      <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a bwg_lightbox\"  data-image-id=\"3854\" href=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/Muong_Thanh_Hue_8.jpg?bwg=1557223082\" data-elementor-open-lightbox=\"no\" >                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"3854\"                   data-width=\"\"                   data-height=\"\"                   data-original=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Muong_Thanh_Hue_8.jpg?bwg=1557223082\"                   src=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Muong_Thanh_Hue_8.jpg?bwg=1557223082\"                   alt=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>        <div class=\"bwg-thumb-description bwg_thumb_description_0\"><span><\/span><\/div>      <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a bwg_lightbox\"  data-image-id=\"3853\" href=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/Muong_Thanh_Hue_9.jpg?bwg=1557223082\" data-elementor-open-lightbox=\"no\" >                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"3853\"                   data-width=\"\"                   data-height=\"\"                   data-original=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Muong_Thanh_Hue_9.jpg?bwg=1557223082\"                   src=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/Muong_Thanh_Hue_9.jpg?bwg=1557223082\"                   alt=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>        <div class=\"bwg-thumb-description bwg_thumb_description_0\"><span><\/span><\/div>      <\/div>          <\/div>    <style>      \/*pagination styles*\/      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 {\t\t\t\ttext-align: center;\t\t\t\tfont-size: 12px;\t\t\t\tfont-family: Ubuntu;\t\t\t\tfont-weight: bold;\t\t\t\tcolor: #666666;\t\t\t\tmargin: 6px 0 4px;\t\t\t\tdisplay: block;      }      @media only screen and (max-width : 320px) {      #bwg_container1_0 #bwg_container2_0 .displaying-num_0 {     \t display: none;      }      }      #bwg_container1_0 #bwg_container2_0 .displaying-num_0 {\t\t\t\tfont-size: 12px;\t\t\t\tfont-family: Ubuntu;\t\t\t\tfont-weight: bold;\t\t\t\tcolor: #666666;\t\t\t\tmargin-right: 10px;\t\t\t\tvertical-align: middle;      }      #bwg_container1_0 #bwg_container2_0 .paging-input_0 {\t\t\t\tfont-size: 12px;\t\t\t\tfont-family: Ubuntu;\t\t\t\tfont-weight: bold;\t\t\t\tcolor: #666666;\t\t\t\tvertical-align: middle;      }      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 a.disabled,      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 a.disabled:hover,      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 a.disabled:focus,\t\t\t#bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 input.bwg_current_page {\t\t\t\tcursor: default;\t\t\t\tcolor: rgba(102, 102, 102, 0.5);      }      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 a,      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 input.bwg_current_page {\t\t\t\tcursor: pointer;\t\t\t\ttext-align: center;\t\t\t\tfont-size: 12px;\t\t\t\tfont-family: Ubuntu;\t\t\t\tfont-weight: bold;\t\t\t\tcolor: #666666;\t\t\t\ttext-decoration: none;\t\t\t\tpadding: 3px 6px;\t\t\t\tmargin: 0;\t\t\t\tborder-radius: 0;\t\t\t\tborder-style: solid;\t\t\t\tborder-width: 1px;\t\t\t\tborder-color: #E3E3E3;\t\t\t\tbackground-color: #FFFFFF;\t\t\t\topacity: 1.00;\t\t\t\tbox-shadow: 0;\t\t\t\ttransition: all 0.3s ease 0s;-webkit-transition: all 0.3s ease 0s;      }      <\/style>      <span class=\"bwg_nav_cont_0\">              <div class=\"tablenav-pages_0\">                  <\/div>                <input type=\"hidden\" id=\"page_number_0\" name=\"page_number_0\" value=\"1\" \/>      <script type=\"text\/javascript\">        function spider_page_0(cur, x, y, load_more) {          if (typeof load_more == \"undefined\") {            var load_more = false;          }          if (jQuery(cur).hasClass('disabled')) {            return false;          }          var items_county_0 = 1;          switch (y) {            case 1:              if (x >= items_county_0) {                document.getElementById('page_number_0').value = items_county_0;              }              else {                document.getElementById('page_number_0').value = x + 1;              }              break;            case 2:              document.getElementById('page_number_0').value = items_county_0;              break;            case -1:              if (x == 1) {                document.getElementById('page_number_0').value = 1;              }              else {                document.getElementById('page_number_0').value = x - 1;              }              break;            case -2:              document.getElementById('page_number_0').value = 1;              break;\t\t\t\t\t\tcase 0:              document.getElementById('page_number_0').value = x;              break;            default:              document.getElementById('page_number_0').value = 1;          }          bwg_ajax('gal_front_form_0', '0', 'bwg_thumbnails_0', '0', '', 'gallery', 0, '', '', load_more, '', 1);        }                    jQuery('.first-page-0').on('click', function () {              spider_page_0(this, 1, -2, 'numeric');              return false;            });            jQuery('.prev-page-0').on('click', function () {              spider_page_0(this, 1, -1, 'numeric');              return false;            });            jQuery('.next-page-0').on('click', function () {              spider_page_0(this, 1, 1, 'numeric');              return false;            });            jQuery('.last-page-0').on('click', function () {              spider_page_0(this, 1, 2, 'numeric');              return false;            });        \t\t\t\t\/* Change page on input enter. *\/        function bwg_change_page_0( e, that ) {          if (  e.key == 'Enter' ) {            var to_page = parseInt(jQuery(that).val());            var pages_count = jQuery(that).parents(\".pagination-links\").data(\"pages-count\");            var current_url_param = jQuery(that).attr('data-url-info');            if (to_page > pages_count) {              to_page = 1;            }\t \t\t\t\t\t\t\t\t\t\t\t\tspider_page_0(this, to_page, 0, 'numeric');\t\t\t\t\t\t\treturn false;\t\t\t\t\t\t          }          return true;        }        jQuery('.bwg_load_btn_0').on('click', function () {            spider_page_0(this, 1, 1, true);            return false;        });      <\/script>      <\/span>                <\/div>        <\/form>          <style>          #bwg_container1_0 #bwg_container2_0 #spider_popup_overlay_0 {          background-color: #EEEEEE;          opacity: 0.60;          }          <\/style>        <div id=\"bwg_spider_popup_loading_0\" class=\"bwg_spider_popup_loading\"><\/div>        <div id=\"spider_popup_overlay_0\" class=\"spider_popup_overlay\" onclick=\"spider_destroypopup(1000)\"><\/div>        <input type=\"hidden\" id=\"bwg_random_seed_0\" value=\"532789538\">                <\/div>    <\/div>    <script>      if (document.readyState === 'complete') {        if( typeof bwg_main_ready == 'function' ) {          if ( jQuery(\"#bwg_container1_0\").height() ) {            bwg_main_ready(jQuery(\"#bwg_container1_0\"));          }        }      } else {        document.addEventListener('DOMContentLoaded', function() {          if( typeof bwg_main_ready == 'function' ) {            if ( jQuery(\"#bwg_container1_0\").height() ) {             bwg_main_ready(jQuery(\"#bwg_container1_0\"));            }          }        });      }    <\/script>    \n","protected":false},"excerpt":{"rendered":"<p>Class: Superior Class \u00a0 Address: No 38 &#8211; Le Loi &#8211; Hue city &#8211; Viet Nam<\/p>\n","protected":false},"author":1,"featured_media":8479,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[67,159,56],"tags":[],"_links":{"self":[{"href":"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/posts\/8475"}],"collection":[{"href":"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/comments?post=8475"}],"version-history":[{"count":2,"href":"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/posts\/8475\/revisions"}],"predecessor-version":[{"id":8481,"href":"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/posts\/8475\/revisions\/8481"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/media\/8479"}],"wp:attachment":[{"href":"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/media?parent=8475"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/categories?post=8475"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/tags?post=8475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}