{"id":8971,"date":"2019-05-29T04:20:16","date_gmt":"2019-05-29T04:20:16","guid":{"rendered":"http:\/\/www.vexploretravel.com\/sites\/?p=8971"},"modified":"2019-06-12T08:37:02","modified_gmt":"2019-06-12T08:37:02","slug":"hanoi-la-siesta-central-hotel-spa","status":"publish","type":"post","link":"http:\/\/www.vexploretravel.com\/sites\/2019\/05\/29\/hanoi-la-siesta-central-hotel-spa\/","title":{"rendered":"Hanoi La Siesta Central Hotel &#038; Spa"},"content":{"rendered":"<p><span style=\"color: #000000;\">Class: Superior Class<\/span><\/p>\n<p><span style=\"color: #000000;\">Address: <span id=\"b_tt_holder_3\" class=\" hp_address_subtitle js-hp_address_subtitle jq_tooltip \" data-source=\"top_link\" data-coords=\",\" data-bbox=\"105.834488777446,21.0141725834269,105.873055222554,21.0501034165731\" data-node_tt_id=\"location_score_tooltip\" data-width=\"350\" data-title=\"\">1B Cau Go Street, Hoan Kiem District,<\/span> Hanoi, Vietnam.<br \/>\n<\/span><\/p>\n<p><span style=\"color: #000000;\"><!--more--><\/span><\/p>\n<p><span style=\"color: #000000;\">Location: Ideally located in the heart of Hanoi`s Old Quarter, just a minute`s walk to the famous Hoan Kiem Lake (Lake of Sword Restored) &amp; to the Water Puppet theatre, the hotels` location are very convenient for guests with shopping and banking facilities, as well as eating and entertainment options all very close by. The hotel is a 50 minutes from Noibai Int`l Airport and 15 minutes from Hanoi Railway Station or the Bus Station.<\/span><\/p>\n<p><iframe loading=\"lazy\" style=\"border: 0;\" src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m14!1m8!1m3!1d14896.065308879348!2d105.8536752!3d21.0320327!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x0%3A0x2004013f65c3b2ac!2sHanoi+La+Siesta+Central+Hotel+%26+Spa!5e0!3m2!1sen!2sus!4v1559103594347!5m2!1sen!2sus\" width=\"600\" height=\"450\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p><span style=\"color: #000000;\">HOTEL DESCRIPTION<\/span><\/p>\n<p><span style=\"color: #000000;\">Hanoi La Siesta Central Hotel &amp; Spa An exclusive boutique hotel with a central address No. 1b Cau Go Street in the heart of Hanoi Experience the cultural art of luxury hospitality La Siesta Central hotel &amp; spa is located on Cau Go Street in the middle of Hanoi\u2019s old quarter. Two sides, two views, two atmospheres. The front overlooks food stalls and city roof tops of this vibrant area, while the back gives sweeping views of neighboring captivating Hoan Kiem Lake and surrounding tree tops.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\">ROOM TYPES<\/span><\/p>\n<p><span style=\"color: #000000;\">27 distinguished guestrooms split over five floors are inspired by colonial and period-style elegance.<\/span><\/p>\n<ul>\n<li><span style=\"color: #000000;\">Deluxe Room: 22-25 sqm,\u00a001 King bed or 02 single beds, standing shower.<\/span><\/li>\n<li><span style=\"color: #000000;\">Executive Room: 25-28 sqm, 01 King sized bed, all with open windows.<\/span><\/li>\n<li><span style=\"color: #000000;\">Junior Suite: 23-25 sqm, 01 King sized bed,\u00a0all with open windows.<\/span><\/li>\n<li><span style=\"color: #000000;\">Central Suite Street View: 30-33 sqm, 01 King sized bed, all with open windows.<\/span><\/li>\n<li><span style=\"color: #000000;\">Balcony La Siesta Suite: 32-35 sqm, 01 King sized bed, at the front side, on upper floors with view, all with open windows.<\/span><\/li>\n<li><span style=\"color: #000000;\">Premium Suite La Siesta Balcony: 45 sqm, 01 King sized bed, private balcony and city view, all with open windows, bathtub.<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\">ROOM AMENITIES<\/span><\/p>\n<ul>\n<li><span style=\"color: #000000;\">FREE Wireless internet access<\/span><\/li>\n<li><span style=\"color: #000000;\">Daily complimentary bottled water<\/span><\/li>\n<li><span style=\"color: #000000;\">Daily housekeeping service<\/span><\/li>\n<li><span style=\"color: #000000;\">Wooden floor<\/span><\/li>\n<li><span style=\"color: #000000;\">Central Air-conditioning with Digital individual climate control<\/span><\/li>\n<li><span style=\"color: #000000;\">32\u2019\u2019 flat screen TV with cable program<\/span><\/li>\n<li><span style=\"color: #000000;\">IDD telephone<\/span><\/li>\n<li><span style=\"color: #000000;\">Electronic safe deposit box<\/span><\/li>\n<li><span style=\"color: #000000;\">Refrigerator &amp; Minibar<\/span><\/li>\n<li><span style=\"color: #000000;\">Writing desk &amp; reading lamp<\/span><\/li>\n<li><span style=\"color: #000000;\">Coffee table<\/span><\/li>\n<li><span style=\"color: #000000;\">Tea bags &amp; coffee making facilities<\/span><\/li>\n<li><span style=\"color: #000000;\"> Bathroom with standing shower<\/span><\/li>\n<li><span style=\"color: #000000;\">Alarm clock<\/span><\/li>\n<li><span style=\"color: #000000;\">Weighing scale<\/span><\/li>\n<li><span style=\"color: #000000;\">Hair-dryer &amp; Bathroom Amenities<\/span><\/li>\n<li><span style=\"color: #000000;\">Shaver outlet (220 volts)<\/span><\/li>\n<li><span style=\"color: #000000;\">Electrical adaptor<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\">FACILITIES AND SERVICES<\/span><\/p>\n<ul>\n<li><span style=\"color: #000000;\">Red Bean Central Restaurant<\/span><\/li>\n<li><span style=\"color: #000000;\">Twilight Sky Bar<\/span><\/li>\n<li><span style=\"color: #000000;\">La Spa<\/span><\/li>\n<li><span style=\"color: #000000;\">Afternoon Tea<\/span><\/li>\n<li><span style=\"color: #000000;\">Vietnam Visa<\/span><\/li>\n<li><span style=\"color: #000000;\">Transfer service<\/span><\/li>\n<li><span style=\"color: #000000;\">Tour Desk<\/span><\/li>\n<li><span style=\"color: #000000;\">Concierge Lounge Hours<\/span><\/li>\n<li><span style=\"color: #000000;\">Gift\/newsstand<\/span><\/li>\n<li><span style=\"color: #000000;\">Babysitting<\/span><\/li>\n<li><span style=\"color: #000000;\">Cash machine\/ATM<\/span><\/li>\n<li><span style=\"color: #000000;\">Concierge desk<\/span><\/li>\n<li><span style=\"color: #000000;\">Foreign exchange<\/span><\/li>\n<li><span style=\"color: #000000;\">Housekeeping service daily<\/span><\/li>\n<li><span style=\"color: #000000;\">Laundry on-site<\/span><\/li>\n<\/ul>\n<style id=\"bwg-style-0\">    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails {      width: 754px;              justify-content: center;        margin:0 auto !important;              background-color: rgba(255, 255, 255, 0.00);            padding-left: 4px;      padding-top: 4px;      max-width: 100%;            }        #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item {      justify-content: flex-start;      max-width: 250px;          }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item > a {       margin-right: 4px;       margin-bottom: 4px;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item0 {      padding: 0px;            background-color:rgba(0,0,0, 0.30);      border: 0px none #CCCCCC;      opacity: 1.00;      border-radius: 0;      box-shadow: ;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item1 img {      max-height: none;      max-width: none;      padding: 0 !important;    }         @media only screen and (min-width: 480px) {\t\t#bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item1 img {\t\t\t-webkit-transition: all .3s; transition: all .3s;\t\t}\t\t#bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item1 img:hover {\t\t\t-ms-transform: scale(1.08);\t\t\t-webkit-transform: scale(1.08);\t\t\ttransform: scale(1.08);\t\t}\t\t      }\t    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item1 {      padding-top: 56%;    }        #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-title2,    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-ecommerce2 {      color: #323A45;      font-family: Ubuntu;      font-size: 16px;      font-weight: bold;      padding: 2px;      text-shadow: ;      max-height: 100%;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-thumb-description span {    color: #323A45;    font-family: Ubuntu;    font-size: 12px;    max-height: 100%;    word-wrap: break-word;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-play-icon2 {      font-size: 32px;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-ecommerce2 {      font-size: 19.2px;      color: #323A45;    }    <\/style>    <div id=\"bwg_container1_0\"         class=\"bwg_container bwg_thumbnail bwg_thumbnails\"         data-right-click-protection=\"0\"         data-bwg=\"0\"         data-gallery-type=\"thumbnails\"         data-current-url=\"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/posts\/8971\"         data-lightbox-url=\"http:\/\/www.vexploretravel.com\/sites\/wp-admin\/admin-ajax.php?action=GalleryBox&current_view=0&gallery_id=436&tag=0&theme_id=1&shortcode_id=917&sort_by=order&order_by=asc&current_url=http%3A%2F%2Fwww.vexploretravel.com%2Fsites%2Fwp-json%2Fwp%2Fv2%2Fposts%2F8971\"         data-gallery-id=\"436\"         data-popup-width=\"800\"         data-popup-height=\"500\"         data-is-album=\"gallery\"         data-buttons-position=\"bottom\">      <div id=\"bwg_container2_0\">             <div id=\"ajax_loading_0\" class=\"bwg_loading_div_1\">      <div class=\"bwg_loading_div_2\">        <div class=\"bwg_loading_div_3\">          <div id=\"loading_div_0\" class=\"bwg_spider_ajax_loading\">          <\/div>        <\/div>      <\/div>    <\/div>            <form id=\"gal_front_form_0\"              class=\"bwg-hidden\"              method=\"post\"              action=\"#\"              data-current=\"0\"              data-shortcode-id=\"917\"              data-gallery-type=\"thumbnails\"              data-gallery-id=\"436\"              data-tag=\"0\"              data-album-id=\"0\"              data-theme-id=\"1\"              data-ajax-url=\"http:\/\/www.vexploretravel.com\/sites\/wp-admin\/admin-ajax.php?action=bwg_frontend_data\">          <div id=\"bwg_container3_0\" class=\"bwg-background bwg-background-0\">                <div data-max-count=\"3\"         data-thumbnail-width=\"250\"         data-bwg=\"0\"         data-gallery-id=\"436\"         data-lightbox-url=\"http:\/\/www.vexploretravel.com\/sites\/wp-admin\/admin-ajax.php?action=GalleryBox&current_view=0&gallery_id=436&tag=0&theme_id=1&shortcode_id=917&sort_by=order&order_by=asc&current_url=http%3A%2F%2Fwww.vexploretravel.com%2Fsites%2Fwp-json%2Fwp%2Fv2%2Fposts%2F8971\"         id=\"bwg_thumbnails_0\"         class=\"bwg-container-0 bwg-thumbnails bwg-standard-thumbnails bwg-container bwg-border-box\">            <div class=\"bwg-item\">        <a class=\"bwg-a bwg_lightbox\"  data-image-id=\"4565\" href=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/HN_La_Siesta_Central_1.jpg?bwg=1559104864\" data-elementor-open-lightbox=\"no\" >                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"4565\"                   data-width=\"\"                   data-height=\"\"                   data-original=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/HN_La_Siesta_Central_1.jpg?bwg=1559104864\"                   src=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/HN_La_Siesta_Central_1.jpg?bwg=1559104864\"                   alt=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>        <div class=\"bwg-thumb-description bwg_thumb_description_0\"><span><\/span><\/div>      <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a bwg_lightbox\"  data-image-id=\"4564\" href=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/HN_La_Siesta_Central_2.jpg?bwg=1559104864\" data-elementor-open-lightbox=\"no\" >                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"4564\"                   data-width=\"\"                   data-height=\"\"                   data-original=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/HN_La_Siesta_Central_2.jpg?bwg=1559104864\"                   src=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/HN_La_Siesta_Central_2.jpg?bwg=1559104864\"                   alt=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>        <div class=\"bwg-thumb-description bwg_thumb_description_0\"><span><\/span><\/div>      <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a bwg_lightbox\"  data-image-id=\"4563\" href=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/HN_La_Siesta_Central_3.jpg?bwg=1559104864\" data-elementor-open-lightbox=\"no\" >                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"4563\"                   data-width=\"\"                   data-height=\"\"                   data-original=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/HN_La_Siesta_Central_3.jpg?bwg=1559104864\"                   src=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/HN_La_Siesta_Central_3.jpg?bwg=1559104864\"                   alt=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>        <div class=\"bwg-thumb-description bwg_thumb_description_0\"><span><\/span><\/div>      <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a bwg_lightbox\"  data-image-id=\"4562\" href=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/HN_La_Siesta_Central_4.jpg?bwg=1559104864\" data-elementor-open-lightbox=\"no\" >                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"4562\"                   data-width=\"\"                   data-height=\"\"                   data-original=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/HN_La_Siesta_Central_4.jpg?bwg=1559104864\"                   src=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/HN_La_Siesta_Central_4.jpg?bwg=1559104864\"                   alt=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>        <div class=\"bwg-thumb-description bwg_thumb_description_0\"><span><\/span><\/div>      <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a bwg_lightbox\"  data-image-id=\"4561\" href=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/HN_La_Siesta_Central_5.jpg?bwg=1559104864\" data-elementor-open-lightbox=\"no\" >                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"4561\"                   data-width=\"\"                   data-height=\"\"                   data-original=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/HN_La_Siesta_Central_5.jpg?bwg=1559104864\"                   src=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/HN_La_Siesta_Central_5.jpg?bwg=1559104864\"                   alt=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>        <div class=\"bwg-thumb-description bwg_thumb_description_0\"><span><\/span><\/div>      <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a bwg_lightbox\"  data-image-id=\"4560\" href=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/HN_La_Siesta_Central_6.jpg?bwg=1559104864\" data-elementor-open-lightbox=\"no\" >                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"4560\"                   data-width=\"\"                   data-height=\"\"                   data-original=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/HN_La_Siesta_Central_6.jpg?bwg=1559104864\"                   src=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/HN_La_Siesta_Central_6.jpg?bwg=1559104864\"                   alt=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>        <div class=\"bwg-thumb-description bwg_thumb_description_0\"><span><\/span><\/div>      <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a bwg_lightbox\"  data-image-id=\"4559\" href=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/HN_La_Siesta_Central_7.jpg?bwg=1559104864\" data-elementor-open-lightbox=\"no\" >                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"4559\"                   data-width=\"\"                   data-height=\"\"                   data-original=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/HN_La_Siesta_Central_7.jpg?bwg=1559104864\"                   src=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/HN_La_Siesta_Central_7.jpg?bwg=1559104864\"                   alt=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>        <div class=\"bwg-thumb-description bwg_thumb_description_0\"><span><\/span><\/div>      <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a bwg_lightbox\"  data-image-id=\"4558\" href=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/HN_La_Siesta_Central_8.jpg?bwg=1559104864\" data-elementor-open-lightbox=\"no\" >                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"4558\"                   data-width=\"\"                   data-height=\"\"                   data-original=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/HN_La_Siesta_Central_8.jpg?bwg=1559104864\"                   src=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/HN_La_Siesta_Central_8.jpg?bwg=1559104864\"                   alt=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>        <div class=\"bwg-thumb-description bwg_thumb_description_0\"><span><\/span><\/div>      <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a bwg_lightbox\"  data-image-id=\"4557\" href=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/HN_La_Siesta_Central_9.jpg?bwg=1559104864\" data-elementor-open-lightbox=\"no\" >                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 \">            <div class=\"bwg-item2\">              <img class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"4557\"                   data-width=\"\"                   data-height=\"\"                   data-original=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/HN_La_Siesta_Central_9.jpg?bwg=1559104864\"                   src=\"http:\/\/www.vexploretravel.com\/sites\/wp-content\/uploads\/photo-gallery\/thumb\/HN_La_Siesta_Central_9.jpg?bwg=1559104864\"                   alt=\"\" \/>            <\/div>            <div class=\"\">                                                      <\/div>          <\/div>        <\/div>                        <\/a>        <div class=\"bwg-thumb-description bwg_thumb_description_0\"><span><\/span><\/div>      <\/div>          <\/div>    <style>      \/*pagination styles*\/      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 {\t\t\t\ttext-align: center;\t\t\t\tfont-size: 12px;\t\t\t\tfont-family: Ubuntu;\t\t\t\tfont-weight: bold;\t\t\t\tcolor: #666666;\t\t\t\tmargin: 6px 0 4px;\t\t\t\tdisplay: block;      }      @media only screen and (max-width : 320px) {      #bwg_container1_0 #bwg_container2_0 .displaying-num_0 {     \t display: none;      }      }      #bwg_container1_0 #bwg_container2_0 .displaying-num_0 {\t\t\t\tfont-size: 12px;\t\t\t\tfont-family: Ubuntu;\t\t\t\tfont-weight: bold;\t\t\t\tcolor: #666666;\t\t\t\tmargin-right: 10px;\t\t\t\tvertical-align: middle;      }      #bwg_container1_0 #bwg_container2_0 .paging-input_0 {\t\t\t\tfont-size: 12px;\t\t\t\tfont-family: Ubuntu;\t\t\t\tfont-weight: bold;\t\t\t\tcolor: #666666;\t\t\t\tvertical-align: middle;      }      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 a.disabled,      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 a.disabled:hover,      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 a.disabled:focus,\t\t\t#bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 input.bwg_current_page {\t\t\t\tcursor: default;\t\t\t\tcolor: rgba(102, 102, 102, 0.5);      }      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 a,      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 input.bwg_current_page {\t\t\t\tcursor: pointer;\t\t\t\ttext-align: center;\t\t\t\tfont-size: 12px;\t\t\t\tfont-family: Ubuntu;\t\t\t\tfont-weight: bold;\t\t\t\tcolor: #666666;\t\t\t\ttext-decoration: none;\t\t\t\tpadding: 3px 6px;\t\t\t\tmargin: 0;\t\t\t\tborder-radius: 0;\t\t\t\tborder-style: solid;\t\t\t\tborder-width: 1px;\t\t\t\tborder-color: #E3E3E3;\t\t\t\tbackground-color: #FFFFFF;\t\t\t\topacity: 1.00;\t\t\t\tbox-shadow: 0;\t\t\t\ttransition: all 0.3s ease 0s;-webkit-transition: all 0.3s ease 0s;      }      <\/style>      <span class=\"bwg_nav_cont_0\">              <div class=\"tablenav-pages_0\">                  <\/div>                <input type=\"hidden\" id=\"page_number_0\" name=\"page_number_0\" value=\"1\" \/>      <script type=\"text\/javascript\">        function spider_page_0(cur, x, y, load_more) {          if (typeof load_more == \"undefined\") {            var load_more = false;          }          if (jQuery(cur).hasClass('disabled')) {            return false;          }          var items_county_0 = 1;          switch (y) {            case 1:              if (x >= items_county_0) {                document.getElementById('page_number_0').value = items_county_0;              }              else {                document.getElementById('page_number_0').value = x + 1;              }              break;            case 2:              document.getElementById('page_number_0').value = items_county_0;              break;            case -1:              if (x == 1) {                document.getElementById('page_number_0').value = 1;              }              else {                document.getElementById('page_number_0').value = x - 1;              }              break;            case -2:              document.getElementById('page_number_0').value = 1;              break;\t\t\t\t\t\tcase 0:              document.getElementById('page_number_0').value = x;              break;            default:              document.getElementById('page_number_0').value = 1;          }          bwg_ajax('gal_front_form_0', '0', 'bwg_thumbnails_0', '0', '', 'gallery', 0, '', '', load_more, '', 1);        }                    jQuery('.first-page-0').on('click', function () {              spider_page_0(this, 1, -2, 'numeric');              return false;            });            jQuery('.prev-page-0').on('click', function () {              spider_page_0(this, 1, -1, 'numeric');              return false;            });            jQuery('.next-page-0').on('click', function () {              spider_page_0(this, 1, 1, 'numeric');              return false;            });            jQuery('.last-page-0').on('click', function () {              spider_page_0(this, 1, 2, 'numeric');              return false;            });        \t\t\t\t\/* Change page on input enter. *\/        function bwg_change_page_0( e, that ) {          if (  e.key == 'Enter' ) {            var to_page = parseInt(jQuery(that).val());            var pages_count = jQuery(that).parents(\".pagination-links\").data(\"pages-count\");            var current_url_param = jQuery(that).attr('data-url-info');            if (to_page > pages_count) {              to_page = 1;            }\t \t\t\t\t\t\t\t\t\t\t\t\tspider_page_0(this, to_page, 0, 'numeric');\t\t\t\t\t\t\treturn false;\t\t\t\t\t\t          }          return true;        }        jQuery('.bwg_load_btn_0').on('click', function () {            spider_page_0(this, 1, 1, true);            return false;        });      <\/script>      <\/span>                <\/div>        <\/form>          <style>          #bwg_container1_0 #bwg_container2_0 #spider_popup_overlay_0 {          background-color: #EEEEEE;          opacity: 0.60;          }          <\/style>        <div id=\"bwg_spider_popup_loading_0\" class=\"bwg_spider_popup_loading\"><\/div>        <div id=\"spider_popup_overlay_0\" class=\"spider_popup_overlay\" onclick=\"spider_destroypopup(1000)\"><\/div>        <input type=\"hidden\" id=\"bwg_random_seed_0\" value=\"1966659646\">                <\/div>    <\/div>    <script>      if (document.readyState === 'complete') {        if( typeof bwg_main_ready == 'function' ) {          if ( jQuery(\"#bwg_container1_0\").height() ) {            bwg_main_ready(jQuery(\"#bwg_container1_0\"));          }        }      } else {        document.addEventListener('DOMContentLoaded', function() {          if( typeof bwg_main_ready == 'function' ) {            if ( jQuery(\"#bwg_container1_0\").height() ) {             bwg_main_ready(jQuery(\"#bwg_container1_0\"));            }          }        });      }    <\/script>    \n","protected":false},"excerpt":{"rendered":"<p>Class: Superior Class Address: 1B Cau Go Street, Hoan Kiem District, Hanoi, Vietnam.<\/p>\n","protected":false},"author":1,"featured_media":8976,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[65,106,56],"tags":[],"_links":{"self":[{"href":"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/posts\/8971"}],"collection":[{"href":"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/comments?post=8971"}],"version-history":[{"count":3,"href":"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/posts\/8971\/revisions"}],"predecessor-version":[{"id":8979,"href":"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/posts\/8971\/revisions\/8979"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/media\/8976"}],"wp:attachment":[{"href":"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/media?parent=8971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/categories?post=8971"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.vexploretravel.com\/sites\/wp-json\/wp\/v2\/tags?post=8971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}